{"id":15,"count":2,"description":"","link":"https:\/\/www.full-metal-holiday.com\/en\/category\/programm\/","name":"Program","slug":"programm","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programm Archive - Full Metal Holiday<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.full-metal-holiday.com\/en\/category\/programm\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programm Archive - Full Metal Holiday\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.full-metal-holiday.com\/en\/category\/programm\/\" \/>\n<meta property=\"og:site_name\" content=\"Full Metal Holiday\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.full-metal-holiday.com\/category\/programm\/\",\"url\":\"https:\/\/www.full-metal-holiday.com\/category\/programm\/\",\"name\":\"Programm Archive - Full Metal Holiday\",\"isPartOf\":{\"@id\":\"https:\/\/www.full-metal-holiday.com\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.full-metal-holiday.com\/category\/programm\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.full-metal-holiday.com\/category\/programm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.full-metal-holiday.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.full-metal-holiday.com\/de\/#website\",\"url\":\"https:\/\/www.full-metal-holiday.com\/de\/\",\"name\":\"Full Metal Holiday\",\"description\":\"Full Metal Holiday\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.full-metal-holiday.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programm Archive - Full Metal Holiday","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.full-metal-holiday.com\/en\/category\/programm\/","og_locale":"en_GB","og_type":"article","og_title":"Programm Archive - Full Metal Holiday","og_url":"https:\/\/www.full-metal-holiday.com\/en\/category\/programm\/","og_site_name":"Full Metal Holiday","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.full-metal-holiday.com\/category\/programm\/","url":"https:\/\/www.full-metal-holiday.com\/category\/programm\/","name":"Programm Archive - Full Metal Holiday","isPartOf":{"@id":"https:\/\/www.full-metal-holiday.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.full-metal-holiday.com\/category\/programm\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.full-metal-holiday.com\/category\/programm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.full-metal-holiday.com\/"},{"@type":"ListItem","position":2,"name":"Programm"}]},{"@type":"WebSite","@id":"https:\/\/www.full-metal-holiday.com\/de\/#website","url":"https:\/\/www.full-metal-holiday.com\/de\/","name":"Full Metal Holiday","description":"Full Metal Holiday","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.full-metal-holiday.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.full-metal-holiday.com\/en\/wp-json\/wp\/v2\/categories\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.full-metal-holiday.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.full-metal-holiday.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.full-metal-holiday.com\/en\/wp-json\/wp\/v2\/posts?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}